{"id":217,"date":"2022-06-02T19:03:49","date_gmt":"2022-06-02T19:03:49","guid":{"rendered":"https:\/\/wp.fresh\/?page_id=217"},"modified":"2025-08-26T07:13:55","modified_gmt":"2025-08-26T00:13:55","slug":"tim-irid","status":"publish","type":"page","link":"https:\/\/irid.or.id\/en\/tim-irid\/","title":{"rendered":"IRID TEAM"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"217\" class=\"elementor elementor-217\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10c5eaff elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"10c5eaff\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5bc53e7\" data-id=\"5bc53e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43400f0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43400f0c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2561aa7\" data-id=\"2561aa7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55b2678f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"55b2678f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our team consists of researchers, analysts and professionals who are experienced in establishing partnerships with key stakeholders.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3a4248 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3a4248\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-069c506\" data-id=\"069c506\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a872b97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a872b97\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f9ed78e\" data-id=\"1f9ed78e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e13ab5f elementor-widget elementor-widget-heading\" data-id=\"e13ab5f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Boards<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4c43b76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c43b76\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c9dd880\" data-id=\"c9dd880\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94bcb73 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"94bcb73\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-4287\" class=\"omw-open-modal\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/Staff-foto-1024x768-4.png\" class=\"attachment-full size-full wp-image-4282\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/Staff-foto-1024x768-4.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/Staff-foto-1024x768-4-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/Staff-foto-1024x768-4-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/Staff-foto-1024x768-4-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/Staff-foto-1024x768-4-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-4287\" class=\"omw-open-modal\">Salman Al Farisi<\/a><\/h3><p class=\"elementor-image-box-description\">Chair of Board<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78a3fbd\" data-id=\"78a3fbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b312436 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b312436\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-4286\" class=\"omw-open-modal\" tabindex=\"-1\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Amanda-Katili-Niode.png\" class=\"attachment-full size-full wp-image-6553\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Amanda-Katili-Niode.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Amanda-Katili-Niode-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Amanda-Katili-Niode-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Amanda-Katili-Niode-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Amanda-Katili-Niode-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-4286\" class=\"omw-open-modal\">Amanda Katili Niode<\/a><\/h3><p class=\"elementor-image-box-description\">Board Member<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac2cea4 elementor-widget elementor-widget-heading\" data-id=\"ac2cea4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Directors<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-217d94d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"217d94d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0eeabda\" data-id=\"0eeabda\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-913f7d8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"913f7d8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-1825\" class=\"omw-open-modal\" tabindex=\"-1\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/KS-new-2-RESIZE.png\" class=\"attachment-full size-full wp-image-4002\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/KS-new-2-RESIZE.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/KS-new-2-RESIZE-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/KS-new-2-RESIZE-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/KS-new-2-RESIZE-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/KS-new-2-RESIZE-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-1825\" class=\"omw-open-modal\">Moekti Handajani (Kuki) Soejachmoen<\/a><\/h3><p class=\"elementor-image-box-description\">EXECUTIVE DIRECTOR<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a8d1c46\" data-id=\"a8d1c46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eeadada elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"eeadada\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-1841\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/AAM-new-2-RESIZE.png\" class=\"attachment-large size-large wp-image-4008\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/AAM-new-2-RESIZE.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/AAM-new-2-RESIZE-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/AAM-new-2-RESIZE-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/AAM-new-2-RESIZE-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/AAM-new-2-RESIZE-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-1841\" class=\"omw-open-modal\">Andri Akbar Marthen<\/a><\/h3><p class=\"elementor-image-box-description\">RESEARCH DIRECTOR<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d28e4d2\" data-id=\"d28e4d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46ce50f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"46ce50f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-1842\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/HI-new-2-RESIZE.png\" class=\"attachment-full size-full wp-image-4006\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/HI-new-2-RESIZE.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/HI-new-2-RESIZE-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/HI-new-2-RESIZE-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/HI-new-2-RESIZE-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/HI-new-2-RESIZE-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-1842\" class=\"omw-open-modal\">Henriette Imelda<\/a><\/h3><p class=\"elementor-image-box-description\">POLICY ADVOCACY DIRECTOR<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-efdad7e elementor-widget elementor-widget-heading\" data-id=\"efdad7e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">staff<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99340d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99340d3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1210ff5\" data-id=\"1210ff5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdd545b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cdd545b\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-1867\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/ST-new-2-RESIZE.png\" class=\"attachment-full size-full wp-image-4000\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/ST-new-2-RESIZE.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/ST-new-2-RESIZE-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/ST-new-2-RESIZE-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/ST-new-2-RESIZE-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/ST-new-2-RESIZE-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-1867\" class=\"omw-open-modal\">Sandra Juliana Tobing<\/a><\/h3><p class=\"elementor-image-box-description\">Operational Officer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69c1d93 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"69c1d93\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-6179\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Hani-Jr-Polad.png\" class=\"attachment-full size-full wp-image-6181\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Hani-Jr-Polad.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Hani-Jr-Polad-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Hani-Jr-Polad-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Hani-Jr-Polad-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Hani-Jr-Polad-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-6179\" class=\"omw-open-modal\">Adhani Putri Andini<\/a><\/h3><p class=\"elementor-image-box-description\">Junior Policy Advocacy Officer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74d68a6 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"74d68a6\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-4141\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Faisol-Amir.png\" class=\"attachment-full size-full wp-image-4575\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Faisol-Amir.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Faisol-Amir-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Faisol-Amir-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Faisol-Amir-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Faisol-Amir-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-4141\" class=\"omw-open-modal\">Faisol Amir<\/a><\/h3><p class=\"elementor-image-box-description\">Researcher<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-440ca92 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"440ca92\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-6178\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Amel-Jr-Comms-Officer.png\" class=\"attachment-full size-full wp-image-6180\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Amel-Jr-Comms-Officer.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Amel-Jr-Comms-Officer-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Amel-Jr-Comms-Officer-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Amel-Jr-Comms-Officer-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/02\/Amel-Jr-Comms-Officer-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-6178\" class=\"omw-open-modal\">Dany Amelia gozali<\/a><\/h3><p class=\"elementor-image-box-description\">Junior Communications Officer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-271840b\" data-id=\"271840b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bacd265 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bacd265\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-5599\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2024\/10\/Staff-foto-1024x768-7.png\" class=\"attachment-full size-full wp-image-5602\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2024\/10\/Staff-foto-1024x768-7.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/10\/Staff-foto-1024x768-7-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/10\/Staff-foto-1024x768-7-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/10\/Staff-foto-1024x768-7-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/10\/Staff-foto-1024x768-7-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-5599\" class=\"omw-open-modal\">Muhammad Jamil<\/a><\/h3><p class=\"elementor-image-box-description\">Finance Officer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ce4050 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5ce4050\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-4570\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Dhana-1.png\" class=\"attachment-full size-full wp-image-4580\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Dhana-1.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Dhana-1-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Dhana-1-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Dhana-1-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Dhana-1-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-4570\" class=\"omw-open-modal\">Hardhana dinaring danastri<\/a><\/h3><p class=\"elementor-image-box-description\">Junior Policy Advocacy Officer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50613e6 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"50613e6\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-4267\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/3.png\" class=\"attachment-full size-full wp-image-4261\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/3.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/3-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/3-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/3-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/10\/3-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-4267\" class=\"omw-open-modal\">Halimah<\/a><\/h3><p class=\"elementor-image-box-description\">Communications Officer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3a95a0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e3a95a0\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-6499\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Ratna-Ayu-Multimedia-Off.png\" class=\"attachment-full size-full wp-image-6500\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Ratna-Ayu-Multimedia-Off.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Ratna-Ayu-Multimedia-Off-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Ratna-Ayu-Multimedia-Off-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Ratna-Ayu-Multimedia-Off-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/04\/Ratna-Ayu-Multimedia-Off-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-6499\" class=\"omw-open-modal\">Ratna Ayu Lestari<\/a><\/h3><p class=\"elementor-image-box-description\">Multimedia Officer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b50c5a8\" data-id=\"b50c5a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3449c2 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f3449c2\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-1855\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/JT-new-2-RESIZE.png\" class=\"attachment-full size-full wp-image-4001\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/JT-new-2-RESIZE.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/JT-new-2-RESIZE-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/JT-new-2-RESIZE-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/JT-new-2-RESIZE-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/07\/JT-new-2-RESIZE-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-1855\" class=\"omw-open-modal\">Julia Theresya<\/a><\/h3><p class=\"elementor-image-box-description\">Policy Advocacy Officer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b16ccf5 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b16ccf5\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-4571\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Novi-1.png\" class=\"attachment-full size-full wp-image-4579\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Novi-1.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Novi-1-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Novi-1-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Novi-1-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2024\/03\/Jr.-PA-Novi-1-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-4571\" class=\"omw-open-modal\">anindya novianti putri<\/a><\/h3><p class=\"elementor-image-box-description\">Junior Policy Advocacy Officer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f37c248 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f37c248\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-2995\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"578\" height=\"432\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/06\/maria_edited_-_4.3-removebg-preview-1.png\" class=\"attachment-full size-full wp-image-3908\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2023\/06\/maria_edited_-_4.3-removebg-preview-1.png 578w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/06\/maria_edited_-_4.3-removebg-preview-1-300x224.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/06\/maria_edited_-_4.3-removebg-preview-1-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2023\/06\/maria_edited_-_4.3-removebg-preview-1-200x149.png 200w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-2995\" class=\"omw-open-modal\">Maria Putri Adianti<\/a><\/h3><p class=\"elementor-image-box-description\">Communications Officer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f00d6f0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f00d6f0\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#omw-6005\" class=\"omw-open-modal\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/irid.or.id\/wp-content\/uploads\/2025\/01\/Mas-Yakub.png\" class=\"attachment-full size-full wp-image-6006\" alt=\"\" srcset=\"https:\/\/irid.or.id\/wp-content\/uploads\/2025\/01\/Mas-Yakub.png 1024w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/01\/Mas-Yakub-300x225.png 300w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/01\/Mas-Yakub-768x576.png 768w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/01\/Mas-Yakub-16x12.png 16w, https:\/\/irid.or.id\/wp-content\/uploads\/2025\/01\/Mas-Yakub-200x150.png 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"#omw-6005\" class=\"omw-open-modal\">Ahmad Yakub Putra Pratama<\/a><\/h3><p class=\"elementor-image-box-description\">Operational Assistant<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d49e17f\" data-id=\"d49e17f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-47fede0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47fede0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-f273735\" data-id=\"f273735\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-5d1595c\" data-id=\"5d1595c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-f909dad\" data-id=\"f909dad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-a80a4ed\" data-id=\"a80a4ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-d828d2e\" data-id=\"d828d2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f196441 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f196441\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-0be7c63\" data-id=\"0be7c63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-58beaa2\" data-id=\"58beaa2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-3c27d75\" data-id=\"3c27d75\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-aa92eae\" data-id=\"aa92eae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-f83ed33\" data-id=\"f83ed33\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63dcab0 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"63dcab0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a96997\" data-id=\"1a96997\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Tim kami terdiri dari para peneliti, analis dan profesional yang berpengalaman dalam menjalin kemitraan dengan para pemangku kepentingan kunci. DEWAN Salman Al<\/p>\n<div><a class=\"more-link\" href=\"https:\/\/irid.or.id\/en\/tim-irid\/\"><\/a><\/div>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","footnotes":""},"class_list":["post-217","page","type-page","status-publish","hentry","entry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/pages\/217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/comments?post=217"}],"version-history":[{"count":423,"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/pages\/217\/revisions"}],"predecessor-version":[{"id":7234,"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/pages\/217\/revisions\/7234"}],"wp:attachment":[{"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/media?parent=217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}