{"id":249,"count":3,"description":"","link":"https:\/\/irid.or.id\/en\/category\/artikel-kegiatan\/","name":"Event Article","slug":"artikel-kegiatan","taxonomy":"category","parent":0,"meta":[],"acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/irid.or.id\/en\/category\/artikel-kegiatan\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/249\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/irid.or.id\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/irid.or.id\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/category\\\/artikel-kegiatan\\\/#listItem\",\"name\":\"Artikel Kegiatan\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/category\\\/artikel-kegiatan\\\/#listItem\",\"position\":2,\"name\":\"Artikel Kegiatan\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/irid.or.id\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/249\\\/#collectionpage\",\"url\":\"https:\\\/\\\/irid.or.id\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/249\\\/\",\"name\":\"Artikel Kegiatan - irid.or.id\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/249\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/#organization\",\"name\":\"irid.or.id\",\"description\":\"Just another WordPress site\",\"url\":\"https:\\\/\\\/irid.or.id\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/irid.or.id\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/IRID_main-conf_54mm_red-white_on-photo-back-1.png\",\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/249\\\/#organizationLogo\",\"width\":130,\"height\":70},\"image\":{\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/249\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/irid.or.id\\\/en\\\/\",\"name\":\"irid.or.id\",\"description\":\"Just another WordPress site\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/irid.or.id\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Artikel Kegiatan - irid.or.id","description":"","canonical_url":"https:\/\/irid.or.id\/en\/category\/artikel-kegiatan\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/categories\/249\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/irid.or.id\/en#listItem","position":1,"name":"Home","item":"https:\/\/irid.or.id\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/irid.or.id\/en\/category\/artikel-kegiatan\/#listItem","name":"Artikel Kegiatan"}},{"@type":"ListItem","@id":"https:\/\/irid.or.id\/en\/category\/artikel-kegiatan\/#listItem","position":2,"name":"Artikel Kegiatan","previousItem":{"@type":"ListItem","@id":"https:\/\/irid.or.id\/en#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/categories\/249\/#collectionpage","url":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/categories\/249\/","name":"Artikel Kegiatan - irid.or.id","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/irid.or.id\/en\/#website"},"breadcrumb":{"@id":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/categories\/249\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/irid.or.id\/en\/#organization","name":"irid.or.id","description":"Just another WordPress site","url":"https:\/\/irid.or.id\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/irid.or.id\/wp-content\/uploads\/2022\/07\/IRID_main-conf_54mm_red-white_on-photo-back-1.png","@id":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/categories\/249\/#organizationLogo","width":130,"height":70},"image":{"@id":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/categories\/249\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/irid.or.id\/en\/#website","url":"https:\/\/irid.or.id\/en\/","name":"irid.or.id","description":"Just another WordPress site","inLanguage":"en-GB","publisher":{"@id":"https:\/\/irid.or.id\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/irid.or.id\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArtikel Kegiatan\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/irid.or.id\/en"},{"label":"Artikel Kegiatan","link":"https:\/\/irid.or.id\/en\/category\/artikel-kegiatan\/"}],"_links":{"self":[{"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/categories\/249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/irid.or.id\/en\/wp-json\/wp\/v2\/posts?categories=249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}